{"id":700,"date":"2017-02-01T09:00:49","date_gmt":"2017-02-01T09:00:49","guid":{"rendered":"http:\/\/2017.alicante.wordcamp.org\/?p=700"},"modified":"2017-02-10T15:32:48","modified_gmt":"2017-02-10T14:32:48","slug":"juan-segui-ponente-de-la-wordcamp-alicante-2017","status":"publish","type":"post","link":"https:\/\/alicante.wordcamp.org\/2017\/juan-segui-ponente-de-la-wordcamp-alicante-2017\/","title":{"rendered":"Juan Segu\u00ed, ponente de la WordCamp Alicante 2017"},"content":{"rendered":"<p>Os presentamos a Juan Segu\u00ed.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-701\" src=\"http:\/\/2017.alicante.wordcamp.org\/files\/2017\/01\/juan-segui-wordcamp-alicante.jpg\" alt=\"\" width=\"536\" height=\"300\" srcset=\"https:\/\/alicante.wordcamp.org\/2017\/files\/2017\/01\/juan-segui-wordcamp-alicante.jpg 536w, https:\/\/alicante.wordcamp.org\/2017\/files\/2017\/01\/juan-segui-wordcamp-alicante-300x168.jpg 300w, https:\/\/alicante.wordcamp.org\/2017\/files\/2017\/01\/juan-segui-wordcamp-alicante-500x280.jpg 500w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/p>\n<p>Emprendedor y profesor. Ingeniero t\u00e9cnico de telecomunicaci\u00f3n e ingeniero superior en organizaci\u00f3n industrial por la Universidad Polit\u00e9cnica de Valencia (UPV) y m\u00e1ster en software libre por la Universitat Oberta de Catalunya (UOC).<\/p>\n<p>Emprendedor en serie, actualmente ha montado varias empresas en diferentes \u00e1mbitos. CEO de <a href=\"http:\/\/acceseo.com\" rel=\"nofollow\">acceseo<\/a>. Colabora como profesor en el M\u00e1ster en comercio electr\u00f3nico de la Universidad Polit\u00e9cnica de Valencia en el Programa Yuzz de Santander Universidades. Adem\u00e1s ha participado con ponente en diferentes eventos y conferencias.<\/p>\n<p>Actualmente entre Estados Unidos y Espa\u00f1a.<\/p>\n<p><a href=\"https:\/\/2017.alicante.wordcamp.org\/tickets-wordcamp-alicante-2017\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-738\" src=\"http:\/\/2017.alicante.wordcamp.org\/files\/2017\/01\/boton-comprar-entradas.jpg\" alt=\"\" width=\"300\" height=\"80\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os presentamos a Juan Segu\u00ed. Emprendedor y profesor. Ingeniero t\u00e9cnico de telecomunicaci\u00f3n e ingeniero superior en organizaci\u00f3n industrial por la Universidad Polit\u00e9cnica de Valencia (UPV) y m\u00e1ster en software libre por la Universitat Oberta de Catalunya (UOC). Emprendedor en serie, &hellip; <a href=\"https:\/\/alicante.wordcamp.org\/2017\/juan-segui-ponente-de-la-wordcamp-alicante-2017\/\">Seguir leyendo <span class=\"assistive-text\">Juan Segu\u00ed, ponente de la WordCamp Alicante 2017<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":10787905,"featured_media":701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10633],"tags":[],"class_list":["post-700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ponentes"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheQ4z-bi","jetpack_featured_media_url":"https:\/\/alicante.wordcamp.org\/2017\/files\/2017\/01\/juan-segui-wordcamp-alicante.jpg","_links":{"self":[{"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/10787905"}],"replies":[{"embeddable":true,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":2,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":935,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/700\/revisions\/935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alicante.wordcamp.org\/2017\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}